{"id":6566,"date":"2025-05-14T09:50:47","date_gmt":"2025-05-14T07:50:47","guid":{"rendered":"https:\/\/cdu-meerbusch.de\/?post_type=personen&#038;p=6566"},"modified":"2026-01-06T12:34:57","modified_gmt":"2026-01-06T11:34:57","slug":"lydia-tittes","status":"publish","type":"personen","link":"https:\/\/cdu-meerbusch.de\/en\/personen\/lydia-tittes\/","title":{"rendered":"Lydia Tittes"},"content":{"rendered":"<p><strong>CDU, because ...<\/strong><\/p>\n<p>We need an economic turnaround as quickly as possible. This will only succeed with the CDU and Friedrich Merz at the helm!<\/p>\n<p><strong>What is particularly important to me for Meerbusch ...<\/strong><\/p>\n<p>Making Meerbusch even more attractive as a location - driving forward digitalisation to attract (young) families, but also to attract small and medium-sized enterprises, and expanding Meerbusch as a smart city<\/p>\n<p><strong>Functions, offices, experience etc. :<\/strong><\/p>\n<p>Councillor of the town of Wiehl (School &amp; Education committees) until May 2025, member of the Supervisory Board of Oberberg Hospital, board member of the CDU Oberberg (press spokeswoman), and deputy chairwoman of the JU Oberberg<\/p>\n<p><strong>Hobbies:<\/strong><\/p>\n<p>Tennis, padel, weight training, jogging, yoga, piano, travelling<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":6858,"template":"","meta":{"wahlkreiskandidat_2025":["ja"]},"stadt":[63,64],"class_list":["post-6566","personen","type-personen","status-publish","has-post-thumbnail","hentry","stadt-ratsfraktion","stadt-stadtverodnete-wahlkreisbetreuer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lydia Tittes | CDU Meerbusch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cdu-meerbusch.de\/en\/personen\/lydia-tittes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lydia Tittes | CDU Meerbusch\" \/>\n<meta property=\"og:description\" content=\"CDU, weil \u2026 wir schnellstm\u00f6glich eine Wirtschaftswende ben\u00f6tigen. Diese gelingt nur mit der CDU und Friedrich Merz an der Spitze! Was mir f\u00fcr Meerbusch besonders wichtig ist \u2026 Meerbusch als Standort weiter attraktivieren &#8211; f\u00fcr die Gewinnung (junger) Familien, aber auch f\u00fcr die Ansiedlung kleiner und mittelst\u00e4ndischer Unternehmen die Digitalisierung vorantreiben sowie Meerbusch als Smart [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cdu-meerbusch.de\/en\/personen\/lydia-tittes\/\" \/>\n<meta property=\"og:site_name\" content=\"CDU Meerbusch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T11:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/lydia-tittes-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ProfilePage\"],\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/\",\"url\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/\",\"name\":\"Lydia Tittes | CDU Meerbusch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdu-meerbusch.de\\\/wp-content\\\/uploads\\\/lydia-tittes-1.jpg\",\"datePublished\":\"2025-05-14T07:50:47+00:00\",\"dateModified\":\"2026-01-06T11:34:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdu-meerbusch.de\\\/wp-content\\\/uploads\\\/lydia-tittes-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cdu-meerbusch.de\\\/wp-content\\\/uploads\\\/lydia-tittes-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cdu-meerbusch.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personen\",\"item\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lydia Tittes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#website\",\"url\":\"https:\\\/\\\/cdu-meerbusch.de\\\/\",\"name\":\"CDU Meerbusch\",\"description\":\"gut Leben in Meerbusch\",\"publisher\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#organization\"},\"alternateName\":\"CDU Meerbusch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cdu-meerbusch.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#organization\",\"name\":\"CDU Meerbusch\",\"url\":\"https:\\\/\\\/cdu-meerbusch.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdu-meerbusch.de\\\/wp-content\\\/uploads\\\/cdu-gesamtlogo.png\",\"contentUrl\":\"https:\\\/\\\/cdu-meerbusch.de\\\/wp-content\\\/uploads\\\/cdu-gesamtlogo.png\",\"width\":418,\"height\":120,\"caption\":\"CDU Meerbusch\"},\"image\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cdu-meerbusch.de\\\/personen\\\/lydia-tittes\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lydia Tittes | CDU Meerbusch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cdu-meerbusch.de\/en\/personen\/lydia-tittes\/","og_locale":"en_GB","og_type":"article","og_title":"Lydia Tittes | CDU Meerbusch","og_description":"CDU, weil \u2026 wir schnellstm\u00f6glich eine Wirtschaftswende ben\u00f6tigen. Diese gelingt nur mit der CDU und Friedrich Merz an der Spitze! Was mir f\u00fcr Meerbusch besonders wichtig ist \u2026 Meerbusch als Standort weiter attraktivieren &#8211; f\u00fcr die Gewinnung (junger) Familien, aber auch f\u00fcr die Ansiedlung kleiner und mittelst\u00e4ndischer Unternehmen die Digitalisierung vorantreiben sowie Meerbusch als Smart [&hellip;]","og_url":"https:\/\/cdu-meerbusch.de\/en\/personen\/lydia-tittes\/","og_site_name":"CDU Meerbusch","article_modified_time":"2026-01-06T11:34:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/lydia-tittes-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ProfilePage"],"@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/","url":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/","name":"Lydia Tittes | CDU Meerbusch","isPartOf":{"@id":"https:\/\/cdu-meerbusch.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/#primaryimage"},"image":{"@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/#primaryimage"},"thumbnailUrl":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/lydia-tittes-1.jpg","datePublished":"2025-05-14T07:50:47+00:00","dateModified":"2026-01-06T11:34:57+00:00","breadcrumb":{"@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/#primaryimage","url":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/lydia-tittes-1.jpg","contentUrl":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/lydia-tittes-1.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cdu-meerbusch.de\/"},{"@type":"ListItem","position":2,"name":"Personen","item":"https:\/\/cdu-meerbusch.de\/personen\/"},{"@type":"ListItem","position":3,"name":"Lydia Tittes"}]},{"@type":"WebSite","@id":"https:\/\/cdu-meerbusch.de\/#website","url":"https:\/\/cdu-meerbusch.de\/","name":"CDU Meerbusch","description":"Living well in Meerbusch","publisher":{"@id":"https:\/\/cdu-meerbusch.de\/#organization"},"alternateName":"CDU Meerbusch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cdu-meerbusch.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cdu-meerbusch.de\/#organization","name":"CDU Meerbusch","url":"https:\/\/cdu-meerbusch.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cdu-meerbusch.de\/#\/schema\/logo\/image\/","url":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/cdu-gesamtlogo.png","contentUrl":"https:\/\/cdu-meerbusch.de\/wp-content\/uploads\/cdu-gesamtlogo.png","width":418,"height":120,"caption":"CDU Meerbusch"},"image":{"@id":"https:\/\/cdu-meerbusch.de\/#\/schema\/logo\/image\/"},"mainEntityOfPage":{"@id":"https:\/\/cdu-meerbusch.de\/personen\/lydia-tittes\/"}}]}},"_links":{"self":[{"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/personen\/6566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/personen"}],"about":[{"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/types\/personen"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/media\/6858"}],"wp:attachment":[{"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/media?parent=6566"}],"wp:term":[{"taxonomy":"stadt","embeddable":true,"href":"https:\/\/cdu-meerbusch.de\/en\/wp-json\/wp\/v2\/stadt?post=6566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}